{"id":53,"count":23,"description":"","link":"https:\/\/www.energiepark.at\/sk\/category\/clear-na-lodi-leithaberge\/","name":"CLEAR! Na lodi Leithaberge","slug":"clear-na-lodi-leithaberge","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.energiepark.at\/sk\/wp-json\/wp\/v2\/categories\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.energiepark.at\/sk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.energiepark.at\/sk\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.energiepark.at\/sk\/wp-json\/wp\/v2\/posts?categories=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}